{"id":4240,"date":"2023-03-14T14:28:45","date_gmt":"2023-03-14T13:28:45","guid":{"rendered":"https:\/\/nauticahotels.com\/veranstaltungen-meetings\/"},"modified":"2025-04-04T10:00:28","modified_gmt":"2025-04-04T08:00:28","slug":"veranstaltungen-meetings","status":"publish","type":"page","link":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/","title":{"rendered":"Veranstaltungen &amp; Meetings"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4240\" class=\"elementor elementor-4240 elementor-321\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27e9867 elementor-section-height-min-height cs-section-content-fullwidth cs-parallax-on-scroll cs_scroll_y_100 elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"27e9867\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"100\" style=\"background-image: none;\" data-cs-background-image=\"https:\/\/cozystay.loftocean.com\/island-resort\/wp-content\/uploads\/sites\/3\/2023\/05\/rhamely-kbOlsfQ5fPE-unsplash.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79d0588 dark-color\" data-id=\"79d0588\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c946610 elementor-widget elementor-widget-cs_title\" data-id=\"c946610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">Verleihen Sie Ihren Veranstaltungen eine neue Dimension<\/span><\/div>\t            <h1 class=\"cs-title\">\n\t                Meetings, Veranstaltungen, Hochzeiten\t            <\/h1>\t            <div class=\"cs-title-text\">\n\t                <p>Wichtige Meilensteine mit Freunden und Familie zu feiern, ist eine der gr\u00f6\u00dften Freuden im Leben.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f2ca20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f2ca20\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc2b27f\" data-id=\"fc2b27f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-412197a elementor-widget elementor-widget-cs_title\" data-id=\"412197a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Herausragende Anl\u00e4sse<\/span><\/div>\t            <h3 class=\"cs-title\">\n\t                Veranstalten Sie Ihr Event in den Nautica Hotels\t            <\/h3>\t            <div class=\"cs-title-text\">\n\t                <p>Unser effizientes, dynamisches und erfahrenes Veranstaltungsteam wird jedes Detail auf Ihre Bed\u00fcrfnisse abstimmen, vom erstklassigen Catering bis zur sorgf\u00e4ltig geplanten Unterhaltung. Sie brauchen nur Ihr Glas zu erheben und den Moment zu genie\u00dfen. Um zu reservieren oder weitere Informationen \u00fcber die Veranstaltungen zu erhalten, kontaktieren Sie uns bitte.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a114c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a114c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e4ee57\" data-id=\"6e4ee57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f482590 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f482590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRufen Sie uns an f\u00fcr ein Angebot\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"tel:+38552600400\">+385 52 600 400<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a373a07\" data-id=\"a373a07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91edd58 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"91edd58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMailen Sie uns f\u00fcr ein Angebot\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"mailto:sold@nauticahotels.com\">sold@nauticahotels.com<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc4f97b elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"cc4f97b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8c05861\" data-id=\"8c05861\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d9ae4 elementor-widget elementor-widget-cs_title\" data-id=\"65d9ae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Arbeiten &amp; Treffen<\/span><\/div>\t            <h4 class=\"cs-title\">\n\t                Meeting-R\u00e4ume\t            <\/h4>\t            <div class=\"cs-title-text\">\n\t                <p>Unser unverwechselbarer Stil tr\u00e4gt dazu bei, die Kreativit\u00e4t f\u00fcr jedes Meeting und jede besondere Veranstaltung zu inspirieren und zu entfachen.<\/p>\n<p>Der Tagungsraum St. Lucija bietet Platz f\u00fcr 8 bis 10 Personen. Der Salon in St. Anton bietet Platz f\u00fcr bis zu 100 Personen, und bei Bedarf kann er auch<span class=\"Apple-converted-space\">  <\/span>kann durch eine isolierte Wand in zwei separate Salons aufgeteilt werden.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d5100d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d5100d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8f827af\" data-id=\"8f827af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ee258 elementor-widget elementor-widget-counter\" data-id=\"31ee258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Meeting Rooms<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-311cd94\" data-id=\"311cd94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f02bd68 elementor-widget elementor-widget-counter\" data-id=\"f02bd68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">G\u00e4ste<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"120\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a03af8 dark-color elementor-invisible\" data-id=\"3a03af8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2724,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/hotel-nautica-meetings-teambuilding-mice-novigrad-istria-croatia-1.jpg&quot;},{&quot;id&quot;:2725,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/hotel-nautica-meetings-teambuilding-mice-novigrad-istria-croatia-2.jpg&quot;},{&quot;id&quot;:2726,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/hotel-nautica-meetings-teambuilding-mice-novigrad-istria-croatia-3.jpg&quot;},{&quot;id&quot;:2727,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/hotel-nautica-meetings-teambuilding-mice-novigrad-istria-croatia-4.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_lazyload&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e55ea05 elementor-widget elementor-widget-spacer\" data-id=\"e55ea05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f88a7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f88a7d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b914741\" data-id=\"b914741\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fd0c6d elementor-widget elementor-widget-cs_title\" data-id=\"5fd0c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Annehmlichkeiten f\u00fcr Meetings<\/span><\/div>\t            <h5 class=\"cs-title\">\n\t                Wir haben unsere Annehmlichkeiten so gestaltet, dass Ihre Veranstaltung von Anfang bis Ende reibungslos abl\u00e4uft.\t            <\/h5>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0eaf9f elementor-widget elementor-widget-cs_info_box\" data-id=\"b0eaf9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_info_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"cs-info-box column-6 valign-top img-top tablet-column-3 mobile-column-2 text-center\">\n                <div class=\"cs-info-box-wrap\">                    <div class=\"cs-info-box-item elementor-repeater-item-276d11f\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-board\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h6 class=\"cs-title cs-info-box-title\">B\u00fcrobedarf\t\t\t\t\t\t\t\t<\/h6>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-11f2846\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-printer\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h6 class=\"cs-title cs-info-box-title\">Drucken im Zimmer\t\t\t\t\t\t\t\t<\/h6>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-f4d8256\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-around\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h6 class=\"cs-title cs-info-box-title\">Versanddienstleistungen\t\t\t\t\t\t\t\t<\/h6>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-01d16f3\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-room-service-2\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h6 class=\"cs-title cs-info-box-title\">Catering verf\u00fcgbar\t\t\t\t\t\t\t\t<\/h6>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-45979ed\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-mug\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h6 class=\"cs-title cs-info-box-title\">Tee- und Kaffeepausen\t\t\t\t\t\t\t\t<\/h6>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-da0be81\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-room-service-1\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h6 class=\"cs-title cs-info-box-title\">Anmeldung zum Meeting\t\t\t\t\t\t\t\t<\/h6>\t                        <\/div>\t                    <\/div>\n                    <\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae32829 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"ae32829\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-363e162 dark-color elementor-invisible\" data-id=\"363e162\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2544,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/wedding-nautica-hotel-novigrad.jpg&quot;},{&quot;id&quot;:2543,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/wedding-nautica-love.jpg&quot;},{&quot;id&quot;:1578,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/silvia-mara-y0u7nji4uXY-unsplash.jpg&quot;},{&quot;id&quot;:2545,&quot;url&quot;:&quot;https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/wedding-nautica-novigrad-hotel.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_lazyload&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4775cc6 elementor-widget elementor-widget-spacer\" data-id=\"4775cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cbd298e\" data-id=\"cbd298e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47b0844 elementor-widget elementor-widget-cs_title\" data-id=\"47b0844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Der ultimative Hochzeitstraum<\/span><\/div>\t            <h4 class=\"cs-title\">\n\t                Ein idyllischer Ort f\u00fcr die perfekte Hochzeit\t            <\/h4>\t            <div class=\"cs-title-text\">\n\t                <p>Ihr perfekter Tag beginnt hier. Das bezaubernde Ambiente, die malerische Umgebung und der au\u00dfergew\u00f6hnliche Service sorgen f\u00fcr eine unvergessliche Feier und machen Ihren besonderen Tag zu einem wahrhaft magischen Ereignis. Feiern Sie Ihre Liebesgeschichte im Nautica Hotel. Wir versprechen Ihnen einen Hochzeitstag, der Ihre Tr\u00e4ume \u00fcbertrifft.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-44b6ed9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44b6ed9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ecb87fd\" data-id=\"ecb87fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e28a9c elementor-widget elementor-widget-counter\" data-id=\"0e28a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Wedding Venues<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9019620\" data-id=\"9019620\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e96b362 elementor-widget elementor-widget-counter\" data-id=\"e96b362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Double Rooms<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"42\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9c894e0\" data-id=\"9c894e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb428d6 elementor-widget elementor-widget-counter\" data-id=\"cb428d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">G\u00e4ste<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Verleihen Sie Ihren Veranstaltungen eine neue Dimension Meetings, Veranstaltungen, Hochzeiten Wichtige Meilensteine mit Freunden und Familie zu feiern, ist eine der gr\u00f6\u00dften Freuden im Leben. Herausragende Anl\u00e4sse Veranstalten Sie Ihr Event in den Nautica Hotels Unser effizientes, dynamisches und erfahrenes Veranstaltungsteam wird jedes Detail auf Ihre Bed\u00fcrfnisse abstimmen, vom erstklassigen Catering bis zur sorgf\u00e4ltig geplanten &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"","cozystay_single_page_custom_sticky_site_header":"","cozystay_single_page_hide_page_title":"on","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-4240","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veranstaltungen &amp; Meetings - Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltungen &amp; Meetings - Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich\" \/>\n<meta property=\"og:description\" content=\"Verleihen Sie Ihren Veranstaltungen eine neue Dimension Meetings, Veranstaltungen, Hochzeiten Wichtige Meilensteine mit Freunden und Familie zu feiern, ist eine der gr\u00f6\u00dften Freuden im Leben. Herausragende Anl\u00e4sse Veranstalten Sie Ihr Event in den Nautica Hotels Unser effizientes, dynamisches und erfahrenes Veranstaltungsteam wird jedes Detail auf Ihre Bed\u00fcrfnisse abstimmen, vom erstklassigen Catering bis zur sorgf\u00e4ltig geplanten ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hotelnautica\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-04T08:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticahotels.com\/wp-content\/uploads\/2024\/06\/deluxe-double-room-hotel-nautica-sea-view-marina21-novigrad-kroatien-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/veranstaltungen-meetings\\\/\",\"url\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/veranstaltungen-meetings\\\/\",\"name\":\"Veranstaltungen &amp; Meetings - Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/#website\"},\"datePublished\":\"2023-03-14T13:28:45+00:00\",\"dateModified\":\"2025-04-04T08:00:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/veranstaltungen-meetings\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticahotels.com\\\/de\\\/veranstaltungen-meetings\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/veranstaltungen-meetings\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen &amp; Meetings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/\",\"name\":\"Hotel Nautica - Wellness & SPA, Free Parking, Pet Friendly\",\"description\":\"Buchen Sie auf der offiziellen Website - Buchen Sie direkt auf der offiziellen Website, um garantiert den besten Preis zu erhalten. Sofortige Best\u00e4tigung. Buchen Sie direkt, um die besten Angebote, flexible Stornierungsm\u00f6glichkeiten und andere Vorteile zu erhalten.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/#organization\"},\"alternateName\":\"Hote Nautica, Novigrad - Cittanova, Istria, Croazia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/#organization\",\"name\":\"Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich\",\"alternateName\":\"Hote Nautica, Novigrad - Cittanova, Istria, Croazia\",\"url\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-hotelNautica_icon512.png\",\"contentUrl\":\"https:\\\/\\\/nauticahotels.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-hotelNautica_icon512.png\",\"width\":512,\"height\":512,\"caption\":\"Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticahotels.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hotelnautica\\\/\",\"https:\\\/\\\/www.instagram.com\\\/marinahotelnautica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltungen &amp; Meetings - Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltungen &amp; Meetings - Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich","og_description":"Verleihen Sie Ihren Veranstaltungen eine neue Dimension Meetings, Veranstaltungen, Hochzeiten Wichtige Meilensteine mit Freunden und Familie zu feiern, ist eine der gr\u00f6\u00dften Freuden im Leben. Herausragende Anl\u00e4sse Veranstalten Sie Ihr Event in den Nautica Hotels Unser effizientes, dynamisches und erfahrenes Veranstaltungsteam wird jedes Detail auf Ihre Bed\u00fcrfnisse abstimmen, vom erstklassigen Catering bis zur sorgf\u00e4ltig geplanten ...","og_url":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/","og_site_name":"Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich","article_publisher":"https:\/\/www.facebook.com\/hotelnautica\/","article_modified_time":"2025-04-04T08:00:28+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/nauticahotels.com\/wp-content\/uploads\/2024\/06\/deluxe-double-room-hotel-nautica-sea-view-marina21-novigrad-kroatien-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/","url":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/","name":"Veranstaltungen &amp; Meetings - Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich","isPartOf":{"@id":"https:\/\/nauticahotels.com\/de\/#website"},"datePublished":"2023-03-14T13:28:45+00:00","dateModified":"2025-04-04T08:00:28+00:00","breadcrumb":{"@id":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nauticahotels.com\/de\/veranstaltungen-meetings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nauticahotels.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen &amp; Meetings"}]},{"@type":"WebSite","@id":"https:\/\/nauticahotels.com\/de\/#website","url":"https:\/\/nauticahotels.com\/de\/","name":"Hotel Nautica - Wellness & SPA, Free Parking, Pet Friendly","description":"Buchen Sie auf der offiziellen Website - Buchen Sie direkt auf der offiziellen Website, um garantiert den besten Preis zu erhalten. Sofortige Best\u00e4tigung. Buchen Sie direkt, um die besten Angebote, flexible Stornierungsm\u00f6glichkeiten und andere Vorteile zu erhalten.","publisher":{"@id":"https:\/\/nauticahotels.com\/de\/#organization"},"alternateName":"Hote Nautica, Novigrad - Cittanova, Istria, Croazia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticahotels.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nauticahotels.com\/de\/#organization","name":"Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich","alternateName":"Hote Nautica, Novigrad - Cittanova, Istria, Croazia","url":"https:\/\/nauticahotels.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nauticahotels.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nauticahotels.com\/wp-content\/uploads\/2024\/05\/cropped-hotelNautica_icon512.png","contentUrl":"https:\/\/nauticahotels.com\/wp-content\/uploads\/2024\/05\/cropped-hotelNautica_icon512.png","width":512,"height":512,"caption":"Hotel Nautica - Wellness &amp; SPA, Kostenloses Parken, Haustierfreundlich"},"image":{"@id":"https:\/\/nauticahotels.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hotelnautica\/","https:\/\/www.instagram.com\/marinahotelnautica\/"]}]}},"_links":{"self":[{"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/pages\/4240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/comments?post=4240"}],"version-history":[{"count":5,"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/pages\/4240\/revisions"}],"predecessor-version":[{"id":7052,"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/pages\/4240\/revisions\/7052"}],"wp:attachment":[{"href":"https:\/\/nauticahotels.com\/de\/wp-json\/wp\/v2\/media?parent=4240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}